{"id":5368,"date":"2026-06-22T11:17:14","date_gmt":"2026-06-22T09:17:14","guid":{"rendered":"https:\/\/adn56.net\/blog\/?p=5368"},"modified":"2026-06-22T11:17:14","modified_gmt":"2026-06-22T09:17:14","slug":"menu-de-la-semaine-du-22-juin-2026","status":"publish","type":"post","link":"https:\/\/adn56.net\/blog\/index.php\/2026\/06\/22\/menu-de-la-semaine-du-22-juin-2026\/","title":{"rendered":"Menu de la semaine du 22 juin 2026"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Bonjour, cette semaine 1 troquet et pas d&rsquo;atelier.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Mercredi, Troquet num\u00e9rique<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Porte ouverte \u00e0 toutes et \u00e0 tous pour discussions et \u00e9changes. Id\u00e9al pour d\u00e9couvrir l&rsquo;association et ses activit\u00e9s. Entraide pour r\u00e9soudre les petits soucis informatiques.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rendez-vous le <strong>Mercredi 24 Juin \u00e0 17:00<\/strong> \u00e0 La Rotonde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ouvert \u00e0 tous<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bonjour, cette semaine 1 troquet et pas d&rsquo;atelier. Mercredi, Troquet num\u00e9rique Porte ouverte \u00e0 toutes et \u00e0 tous pour discussions et \u00e9changes. Id\u00e9al pour d\u00e9couvrir l&rsquo;association et ses activit\u00e9s. Entraide pour r\u00e9soudre les petits soucis informatiques. Rendez-vous le Mercredi 24 Juin \u00e0 17:00 \u00e0 La Rotonde. Ouvert \u00e0 tous<\/p>\n","protected":false},"author":1,"featured_media":3739,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-5368","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vie-de-lassociation"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/adn56.net\/blog\/wp-content\/uploads\/2023\/03\/troquet-e1730115621740.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p82yvs-1oA","_links":{"self":[{"href":"https:\/\/adn56.net\/blog\/index.php\/wp-json\/wp\/v2\/posts\/5368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adn56.net\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adn56.net\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adn56.net\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adn56.net\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=5368"}],"version-history":[{"count":1,"href":"https:\/\/adn56.net\/blog\/index.php\/wp-json\/wp\/v2\/posts\/5368\/revisions"}],"predecessor-version":[{"id":5369,"href":"https:\/\/adn56.net\/blog\/index.php\/wp-json\/wp\/v2\/posts\/5368\/revisions\/5369"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adn56.net\/blog\/index.php\/wp-json\/wp\/v2\/media\/3739"}],"wp:attachment":[{"href":"https:\/\/adn56.net\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=5368"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adn56.net\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=5368"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adn56.net\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=5368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}